{"id":18,"count":2,"description":"","link":"https:\/\/kenyapage.net\/commentary\/tag\/zaiko-langa-langa\/","name":"Zaiko Langa Langa","slug":"zaiko-langa-langa","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zaiko Langa Langa Archives - Kenya Page<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kenyapage.net\/commentary\/tag\/zaiko-langa-langa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zaiko Langa Langa Archives - Kenya Page\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kenyapage.net\/commentary\/tag\/zaiko-langa-langa\/\" \/>\n<meta property=\"og:site_name\" content=\"Kenya Page\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kenyapage.net\/commentary\/wp-content\/uploads\/2015\/12\/warioba-blinn.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/kenyapage.net\\\/commentary\\\/tag\\\/zaiko-langa-langa\\\/\",\"url\":\"https:\\\/\\\/kenyapage.net\\\/commentary\\\/tag\\\/zaiko-langa-langa\\\/\",\"name\":\"Zaiko Langa Langa Archives - Kenya Page\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kenyapage.net\\\/commentary\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kenyapage.net\\\/commentary\\\/tag\\\/zaiko-langa-langa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kenyapage.net\\\/commentary\\\/tag\\\/zaiko-langa-langa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kenyapage.net\\\/commentary\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zaiko Langa Langa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kenyapage.net\\\/commentary\\\/#website\",\"url\":\"https:\\\/\\\/kenyapage.net\\\/commentary\\\/\",\"name\":\"Kenya Page\",\"description\":\"Kenya Music and Sports commentary\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kenyapage.net\\\/commentary\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zaiko Langa Langa Archives - Kenya Page","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kenyapage.net\/commentary\/tag\/zaiko-langa-langa\/","og_locale":"en_US","og_type":"article","og_title":"Zaiko Langa Langa Archives - Kenya Page","og_url":"https:\/\/kenyapage.net\/commentary\/tag\/zaiko-langa-langa\/","og_site_name":"Kenya Page","og_image":[{"width":500,"height":700,"url":"https:\/\/kenyapage.net\/commentary\/wp-content\/uploads\/2015\/12\/warioba-blinn.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kenyapage.net\/commentary\/tag\/zaiko-langa-langa\/","url":"https:\/\/kenyapage.net\/commentary\/tag\/zaiko-langa-langa\/","name":"Zaiko Langa Langa Archives - Kenya Page","isPartOf":{"@id":"https:\/\/kenyapage.net\/commentary\/#website"},"breadcrumb":{"@id":"https:\/\/kenyapage.net\/commentary\/tag\/zaiko-langa-langa\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/kenyapage.net\/commentary\/tag\/zaiko-langa-langa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kenyapage.net\/commentary\/"},{"@type":"ListItem","position":2,"name":"Zaiko Langa Langa"}]},{"@type":"WebSite","@id":"https:\/\/kenyapage.net\/commentary\/#website","url":"https:\/\/kenyapage.net\/commentary\/","name":"Kenya Page","description":"Kenya Music and Sports commentary","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kenyapage.net\/commentary\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/kenyapage.net\/commentary\/wp-json\/wp\/v2\/tags\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kenyapage.net\/commentary\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/kenyapage.net\/commentary\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/kenyapage.net\/commentary\/wp-json\/wp\/v2\/posts?tags=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}